{"id":138,"date":"2026-07-10T06:54:02","date_gmt":"2026-07-10T06:54:02","guid":{"rendered":"https:\/\/gattaca.fr\/?page_id=138"},"modified":"2026-07-10T06:54:03","modified_gmt":"2026-07-10T06:54:03","slug":"reussir-ses-recrutements","status":"publish","type":"page","link":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/","title":{"rendered":"R\u00e9ussir ses recrutements"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1 &#8211; Objectifs de la formation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La formation a pour objectif de permettre \u00e0 la participante d\u2019actualiser ses pratiques professionnelles sur les \u00e9tapes cl\u00e9s du processus de recrutement et de faire \u00e9voluer les techniques et outils de recrutement de l\u2019entreprise en respectant le cadre l\u00e9gal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2 &#8211; Public cible<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Personnels charg\u00e9s du recrutement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3 &#8211; Objectifs p\u00e9dagogiques<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l\u2019issue de la formation, la stagiaire sera capable de&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Appliquer le cadre l\u00e9gal de lutte contre les discriminations et de droit \u00e0 la vie priv\u00e9e lors du d\u00e9ploiement de chacune des \u00e9tapes du processus de recrutement<\/li>\n\n\n\n<li>Faire l\u2019acquisition d\u2019une m\u00e9thodologie permettant de d\u00e9finir les activit\u00e9s du poste \u00e0 pourvoir et le profil des candidats recherch\u00e9s et \u00e9tablir l\u2019analyse de poste<\/li>\n\n\n\n<li>Connaitre les diff\u00e9rents modes de \u00ab\u00a0sourcing\u00a0\u00bb pour mieux les adapter aux diff\u00e9rents types de profils<\/li>\n\n\n\n<li>Cr\u00e9er des outils d\u2019aide \u00e0 la s\u00e9lection des candidats et comprendre l\u2019enjeu de l\u2019entretien t\u00e9l\u00e9phonique<\/li>\n\n\n\n<li>Mettre en application les diff\u00e9rentes m\u00e9thodes d\u2019\u00e9valuation du candidat\u00a0: tests, entretiens, mises en situation\u2026<\/li>\n\n\n\n<li>Appr\u00e9hender les techniques de communication adapt\u00e9es afin de mener efficacement un entretien de recrutement\u00a0: entretien individuel, entretien collectif\u2026<\/li>\n\n\n\n<li>Ma\u00eetriser les m\u00e9thodes et outils permettant d\u2019optimiser la prise de d\u00e9cision<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">4 &#8211; Programme d\u00e9taill\u00e9 de la formation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le cadre l\u00e9gal du recrutement<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le cadre l\u00e9gal de lutte contre les discriminations<\/li>\n\n\n\n<li>L\u2019article 9 du code civil formulant le principe de droit \u00e0 la vie priv\u00e9e<\/li>\n\n\n\n<li>La loi du 31 d\u00e9cembre 1992 portant sur les 6 principes de respect des libert\u00e9s individuelles lors des diff\u00e9rentes \u00e9tapes du processus de recrutement<\/li>\n\n\n\n<li>La loi \u00e9galit\u00e9 citoyennet\u00e9 2017<\/li>\n\n\n\n<li>Les r\u00e8gles relatives \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s et au RGPD<\/li>\n\n\n\n<li>Le D\u00e9fenseur Des Droits<\/li>\n\n\n\n<li>Les sanctions encourues<\/li>\n\n\n\n<li>Les pratiques de diversit\u00e9 \u00e0 toutes les \u00e9tapes du processus de recrutement<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La d\u00e9finition du profil recherch\u00e9<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>le vocabulaire du recrutement<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00e9tier<\/li>\n\n\n\n<li>Emploi, emploi-type, emploi sensible\u2026<\/li>\n\n\n\n<li>Fonction, missions, activit\u00e9s\u2026<\/li>\n\n\n\n<li>Poste de travail<\/li>\n\n\n\n<li>Capacit\u00e9, aptitude\u2026<\/li>\n\n\n\n<li>Comp\u00e9tences, comp\u00e9tences transf\u00e9rables\u2026<\/li>\n\n\n\n<li>R\u00e9f\u00e9rentiel emploi activit\u00e9 comp\u00e9tences, r\u00e9f\u00e9rentiel m\u00e9tier\u2026<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>l\u2019analyse de besoin<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La notion de besoin<\/li>\n\n\n\n<li>Les 10 b\u00e9n\u00e9fices de l\u2019analyse de besoin :<ul><li>En amont de l\u2019entretien<\/li><\/ul><ul><li>Lors de l\u2019\u00e9valuation du candidat<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Pour lutter contre les discriminations<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Les limites de l\u2019analyse de besoin<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La description du\/des postes \u00e0 pourvoir<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les questions cl\u00e9s pour d\u00e9crire le poste\u00a0: gage d\u2019objectivit\u00e9<\/li>\n\n\n\n<li>La description des missions et activit\u00e9s\u00a0: compr\u00e9hension du poste<\/li>\n\n\n\n<li>Les \u00e9l\u00e9ments cl\u00e9s d\u2019une analyse de poste\u00a0:<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le profil du candidat<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les diff\u00e9rents crit\u00e8res de description du profil<ul><li>Crit\u00e8res indispensables, souhait\u00e9s\u2026<\/li><\/ul><ul><li>L\u2019exp\u00e9rience professionnelle requise<\/li><\/ul><ul><li>Le parcours de formation requis<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Les comp\u00e9tences n\u00e9cessaires<ul><li>La notion de Soft Skills<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>La notion de Hard Skills<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>La hi\u00e9rarchisation des crit\u00e8res<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La recherche du candidat et la s\u00e9lection des CV<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>les outils de sourcing<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le choix de la bonne strat\u00e9gie de recherche en fonction des profils<\/li>\n\n\n\n<li>Les nouveaux outils\/canaux de sourcing\u00a0: jobboards, r\u00e9seaux sociaux, forums virtuels, cooptation\u2026)<\/li>\n\n\n\n<li>L\u2019impact de l\u2019Intelligence Artificielle (IA)<\/li>\n\n\n\n<li>La r\u00e9daction et la communication d\u2019annonces ou d\u2019appels \u00e0 candidatures attractifs pour une majorit\u00e9 de candidats<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>le tri des CV<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La r\u00e8gle des 3 tas<\/li>\n\n\n\n<li>Les outils et grilles d&rsquo;aide \u00e0 la s\u00e9lection<\/li>\n\n\n\n<li>L&rsquo;int\u00e9r\u00eat de la pr\u00e9s\u00e9lection t\u00e9l\u00e9phonique<\/li>\n\n\n\n<li>Les 6 phases de l\u2019entretien t\u00e9l\u00e9phonique<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019\u00e9valuation du candidat<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les diff\u00e9rentes m\u00e9thodes d\u2019\u00e9valuation des candidats<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les tests<ul><li>Les principaux tests utilis\u00e9s<\/li><\/ul><ul><li>L\u2019int\u00e9gration des tests dans le processus de recrutement<\/li><\/ul><ul><li>Les avantages et les limites des tests<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Les conditions d\u2019utilisation des tests<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>L\u2019Assessment center<\/li>\n\n\n\n<li>L\u2019entretien individuel<\/li>\n\n\n\n<li>L\u2019entretien collectif<\/li>\n\n\n\n<li>L\u2019entretien multiple<\/li>\n\n\n\n<li>La conception des outils supports de l\u2019\u00e9valuation<ul><li>Les \u00e9l\u00e9ments constitutifs d\u2019un guide d\u2019entretien<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Les diff\u00e9rentes formes de grilles d\u2019\u00e9valuation des comp\u00e9tences des candidats<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les techniques d\u2019entretien de recrutement<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le contenu de l\u2019entretien<\/li>\n\n\n\n<li>La formulation des questions<\/li>\n\n\n\n<li>Les diff\u00e9rents types de questions<\/li>\n\n\n\n<li>La m\u00e9thode STAR<\/li>\n\n\n\n<li>Les erreurs \u00e0 \u00e9viter<\/li>\n\n\n\n<li>Les r\u00e8gles li\u00e9es \u00e0 la prise de notes<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les techniques de communication \u00e0 mobiliser lors de la r\u00e9alisation de l\u2019entretien<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La mise en place d\u2019une relation de confiance avec son interlocuteur<\/li>\n\n\n\n<li>L\u2019\u00e9coute active<\/li>\n\n\n\n<li>Le questionnement<\/li>\n\n\n\n<li>La reformulation et ses diff\u00e9rentes formes<\/li>\n\n\n\n<li>Les techniques de communication assertives<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ce module sera compl\u00e9t\u00e9 par la r\u00e9alisation de mises en situation qui permettront \u00e0 la stagiaire de tester ses propres ressources et de mettre en pratique les bonnes techniques de communication afin d\u2019optimiser le d\u00e9roulement de l\u2019entretien de recrutement.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5 &#8211; M\u00e9thodes, outils de transmission et \u00e9valuation des acquis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La formation propos\u00e9e sera adapt\u00e9e aux besoins et probl\u00e9matiques rencontr\u00e9s par la participante dans le cadre de son activit\u00e9 professionnelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essentiellement pratique, la pertinence de la formation reposera sur le choix des m\u00e9thodes et outils p\u00e9dagogiques&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apports th\u00e9oriques et m\u00e9thodologiques<\/li>\n\n\n\n<li>Ateliers m\u00e9thodologiques de construction des outils supports du recrutement avec utilisation du Mindmapping<\/li>\n\n\n\n<li>Mises en situation d\u2019animation d\u2019entretien de recrutement avec d\u00e9briefe et apports correctifs<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e9ments acquis tout au long de la formation seront mesur\u00e9s au travers de diff\u00e9rents outils et exercices de feedback&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tests d\u2019acquisition des \u00e9l\u00e9ments th\u00e9oriques et m\u00e9thodologiques\u00a0: Quizz, QCM, mises en situation<\/li>\n\n\n\n<li>Construction d\u2019outils supports du recrutement<\/li>\n\n\n\n<li>Techniques d\u2019animation des entretiens de recrutement<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>1 &#8211; Objectifs de la formation La formation a pour objectif de permettre \u00e0 la participante d\u2019actualiser ses pratiques professionnelles sur les \u00e9tapes cl\u00e9s du processus de recrutement et de faire \u00e9voluer les techniques et outils de recrutement de l\u2019entreprise en respectant le cadre l\u00e9gal. 2 &#8211; Public cible Personnels charg\u00e9s du recrutement. 3 &#8211; &#8230; <a title=\"R\u00e9ussir ses recrutements\" class=\"read-more\" href=\"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/\" aria-label=\"En savoir plus sur R\u00e9ussir ses recrutements\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":142,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-138","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9ussir ses recrutements - Gattaca Conseil et Formation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9ussir ses recrutements - Gattaca Conseil et Formation\" \/>\n<meta property=\"og:description\" content=\"1 &#8211; Objectifs de la formation La formation a pour objectif de permettre \u00e0 la participante d\u2019actualiser ses pratiques professionnelles sur les \u00e9tapes cl\u00e9s du processus de recrutement et de faire \u00e9voluer les techniques et outils de recrutement de l\u2019entreprise en respectant le cadre l\u00e9gal. 2 &#8211; Public cible Personnels charg\u00e9s du recrutement. 3 &#8211; ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/\" \/>\n<meta property=\"og:site_name\" content=\"Gattaca Conseil et Formation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T06:54:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gattaca.fr\\\/index.php\\\/qui-sommes-nous\\\/formations-ressources-humaines\\\/reussir-ses-recrutements\\\/\",\"url\":\"https:\\\/\\\/gattaca.fr\\\/index.php\\\/qui-sommes-nous\\\/formations-ressources-humaines\\\/reussir-ses-recrutements\\\/\",\"name\":\"R\u00e9ussir ses recrutements - Gattaca Conseil et Formation\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/gattaca.fr\\\/#website\"},\"datePublished\":\"2026-07-10T06:54:02+00:00\",\"dateModified\":\"2026-07-10T06:54:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gattaca.fr\\\/index.php\\\/qui-sommes-nous\\\/formations-ressources-humaines\\\/reussir-ses-recrutements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gattaca.fr\\\/index.php\\\/qui-sommes-nous\\\/formations-ressources-humaines\\\/reussir-ses-recrutements\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gattaca.fr\\\/index.php\\\/qui-sommes-nous\\\/formations-ressources-humaines\\\/reussir-ses-recrutements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/gattaca.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui sommes-nous ?\",\"item\":\"http:\\\/\\\/gattaca.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Formations Ressources humaines\",\"item\":\"https:\\\/\\\/gattaca.fr\\\/index.php\\\/qui-sommes-nous\\\/formations-ressources-humaines\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"R\u00e9ussir ses recrutements\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/gattaca.fr\\\/#website\",\"url\":\"http:\\\/\\\/gattaca.fr\\\/\",\"name\":\"Gattaca Conseil et Formation\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/gattaca.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/gattaca.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/gattaca.fr\\\/#organization\",\"name\":\"Gattaca Conseil et Formation\",\"url\":\"http:\\\/\\\/gattaca.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/gattaca.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gattaca.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-logo-gattaca-250px.png\",\"contentUrl\":\"https:\\\/\\\/gattaca.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-logo-gattaca-250px.png\",\"width\":250,\"height\":134,\"caption\":\"Gattaca Conseil et Formation\"},\"image\":{\"@id\":\"http:\\\/\\\/gattaca.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9ussir ses recrutements - Gattaca Conseil et Formation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9ussir ses recrutements - Gattaca Conseil et Formation","og_description":"1 &#8211; Objectifs de la formation La formation a pour objectif de permettre \u00e0 la participante d\u2019actualiser ses pratiques professionnelles sur les \u00e9tapes cl\u00e9s du processus de recrutement et de faire \u00e9voluer les techniques et outils de recrutement de l\u2019entreprise en respectant le cadre l\u00e9gal. 2 &#8211; Public cible Personnels charg\u00e9s du recrutement. 3 &#8211; ... Lire la suite","og_url":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/","og_site_name":"Gattaca Conseil et Formation","article_modified_time":"2026-07-10T06:54:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/","url":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/","name":"R\u00e9ussir ses recrutements - Gattaca Conseil et Formation","isPartOf":{"@id":"http:\/\/gattaca.fr\/#website"},"datePublished":"2026-07-10T06:54:02+00:00","dateModified":"2026-07-10T06:54:03+00:00","breadcrumb":{"@id":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/reussir-ses-recrutements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/gattaca.fr\/"},{"@type":"ListItem","position":2,"name":"Qui sommes-nous ?","item":"http:\/\/gattaca.fr\/"},{"@type":"ListItem","position":3,"name":"Formations Ressources humaines","item":"https:\/\/gattaca.fr\/index.php\/qui-sommes-nous\/formations-ressources-humaines\/"},{"@type":"ListItem","position":4,"name":"R\u00e9ussir ses recrutements"}]},{"@type":"WebSite","@id":"http:\/\/gattaca.fr\/#website","url":"http:\/\/gattaca.fr\/","name":"Gattaca Conseil et Formation","description":"","publisher":{"@id":"http:\/\/gattaca.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/gattaca.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/gattaca.fr\/#organization","name":"Gattaca Conseil et Formation","url":"http:\/\/gattaca.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/gattaca.fr\/#\/schema\/logo\/image\/","url":"https:\/\/gattaca.fr\/wp-content\/uploads\/2026\/05\/cropped-logo-gattaca-250px.png","contentUrl":"https:\/\/gattaca.fr\/wp-content\/uploads\/2026\/05\/cropped-logo-gattaca-250px.png","width":250,"height":134,"caption":"Gattaca Conseil et Formation"},"image":{"@id":"http:\/\/gattaca.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/pages\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":2,"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/pages\/138\/revisions"}],"predecessor-version":[{"id":140,"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/pages\/138\/revisions\/140"}],"up":[{"embeddable":true,"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/pages\/142"}],"wp:attachment":[{"href":"https:\/\/gattaca.fr\/index.php\/wp-json\/wp\/v2\/media?parent=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}